{"id":80446,"date":"2016-05-12T02:21:34","date_gmt":"2016-05-12T00:21:34","guid":{"rendered":"http:\/\/localhost\/wordpress\/?p=80446"},"modified":"2016-05-12T02:21:34","modified_gmt":"2016-05-12T00:21:34","slug":"%d9%81%d9%8a%d9%84%d8%a7-%d9%81%d9%8a-%d8%a7%d9%84%d8%a8%d8%b7%d9%8a%d9%86-%d8%ba%d8%a7%d9%81%d8%a7%d8%aa-%d8%a7%d9%84%d8%b4%d9%88%d9%8a%d9%87%d9%8a-%d9%84%d9%84%d8%a7%d9%8a%d8%ac%d8%a7%d8%b1","status":"publish","type":"post","link":"https:\/\/www.satfrequencies.com\/invest\/%d9%81%d9%8a%d9%84%d8%a7-%d9%81%d9%8a-%d8%a7%d9%84%d8%a8%d8%b7%d9%8a%d9%86-%d8%ba%d8%a7%d9%81%d8%a7%d8%aa-%d8%a7%d9%84%d8%b4%d9%88%d9%8a%d9%87%d9%8a-%d9%84%d9%84%d8%a7%d9%8a%d8%ac%d8%a7%d8%b1\/","title":{"rendered":"\u0641\u064a\u0644\u0627 \u0641\u064a \u0627\u0644\u0628\u0637\u064a\u0646 \u063a\u0627\u0641\u0627\u062a \u0627\u0644\u0634\u0648\u064a\u0647\u064a \u0644\u0644\u0627\u064a\u062c\u0627\u0631"},"content":{"rendered":"<div>\n<p align=\"center\" style=\"font:bold 16px 'Times New Roman';line-height:170%;\">\u0641\u064a\u0644\u0627 \u0641\u064a \u0627\u0644\u0628\u0637\u064a\u0646 \u063a\u0627\u0641\u0627\u062a \u0627\u0644\u0634\u0648\u064a\u0647\u064a \u0644\u0644\u0627\u064a\u062c\u0627\u0631  7\u063a\u0631\u0641 \u0645\u0627\u0633\u062a\u0631 \u0645\u0639 \u062d\u0645\u0627\u0645 +\u0645\u062c\u0644\u0633+\u0637\u0639\u0627\u0645+\u0635\u0627\u0644\u062a\u064a\u0646+\u0645\u0637\u0628\u062e+\u063a \u062e\u062f\u0627\u0645\u0629+\u063a \u062d\u0627\u0631\u0633 \u0627\u0631\u0636200*200 \u0639\u0644\u0649 \u0632\u0627\u0648\u064a\u0629 \u0645\u0633\u062c\u062f \u0645\u0637\u0644\u0648\u0628200 \u0627\u0644\u0641 \u0644\u0644\u062a\u0648\u0627\u0635\u06440506196777<br \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/9a1db09efa.jpg\" border=\"0\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/46702fecef.jpg\" border=\"0\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/9b776dc3fc.jpg\" border=\"0\" alt=\"\" \/><br \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/fd5b401a98.jpg\" border=\"0\" alt=\"\" \/><br \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/3ff61867ed.jpg\" border=\"0\" alt=\"\" \/><\/p>\n<div align=\"right\">\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0641\u064a\u0644\u0627 \u0641\u064a \u0627\u0644\u0628\u0637\u064a\u0646 \u063a\u0627\u0641\u0627\u062a \u0627\u0644\u0634\u0648\u064a\u0647\u064a \u0644\u0644\u0627\u064a\u062c\u0627\u0631 7\u063a\u0631\u0641 \u0645\u0627\u0633\u062a\u0631 \u0645\u0639 \u062d\u0645\u0627\u0645 +\u0645\u062c\u0644\u0633+\u0637\u0639\u0627\u0645+\u0635\u0627\u0644\u062a\u064a\u0646+\u0645\u0637\u0628\u062e+\u063a \u062e\u062f\u0627\u0645\u0629+\u063a \u062d\u0627\u0631\u0633 \u0627\u0631\u0636200*200 \u0639\u0644\u0649 \u0632\u0627\u0648\u064a\u0629 \u0645\u0633\u062c\u062f \u0645\u0637\u0644\u0648\u0628200 \u0627\u0644\u0641 \u0644\u0644\u062a\u0648\u0627\u0635\u06440506196777<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-80446","post","type-post","status-publish","format-standard","hentry","category-42"],"_links":{"self":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/80446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/comments?post=80446"}],"version-history":[{"count":0,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/80446\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/media?parent=80446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/categories?post=80446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/tags?post=80446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}