{"id":35002,"date":"2016-02-24T19:49:39","date_gmt":"2016-02-24T17:49:39","guid":{"rendered":"http:\/\/localhost\/wordpress\/?p=35002"},"modified":"2016-02-24T19:49:39","modified_gmt":"2016-02-24T17:49:39","slug":"%d9%85%d8%b7%d9%84%d9%88%d8%a8-%d8%b4%d9%82%d8%a9-%d9%85%d8%b7%d9%84%d8%a9-%d8%b9%d9%84%d9%89-%d8%a8%d8%ad%d9%8a%d8%b1%d8%a9-%d8%a7%d9%84%d8%ae%d8%a7%d9%86","status":"publish","type":"post","link":"https:\/\/www.satfrequencies.com\/invest\/%d9%85%d8%b7%d9%84%d9%88%d8%a8-%d8%b4%d9%82%d8%a9-%d9%85%d8%b7%d9%84%d8%a9-%d8%b9%d9%84%d9%89-%d8%a8%d8%ad%d9%8a%d8%b1%d8%a9-%d8%a7%d9%84%d8%ae%d8%a7%d9%86\/","title":{"rendered":"\u0645\u0637\u0644\u0648\u0628 \u0634\u0642\u0629 \u0645\u0637\u0644\u0629 \u0639\u0644\u0649 \u0628\u062d\u064a\u0631\u0629 \u0627\u0644\u062e\u0627\u0646"},"content":{"rendered":"<div>\n<p>\t\t\t\t\t\t\t\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 <\/p>\n<p> \u0645\u0637\u0644\u0648\u0628 \u0634\u0642\u0629 \u063a\u0631\u0641\u0629 \u0648\u0635\u0627\u0644\u0629 \u0645\u0637\u0644\u0629 \u0639\u0644\u0649 \u0628\u062d\u064a\u0631\u0627\u0646 \u0627\u0644\u062e\u0627\u0646 <\/p>\n<p> \u0644\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0631\u062c\u0627\u0621 \u0627\u0631\u0633\u0627\u0644 \u0631\u0633\u0627\u0644\u0629 \u0639\u0644\u0649 \u0627\u0644\u062e\u0627\u0635 \u0648\u0634\u0643\u0631\u0627<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0645\u0637\u0644\u0648\u0628 \u0634\u0642\u0629 \u063a\u0631\u0641\u0629 \u0648\u0635\u0627\u0644\u0629 \u0645\u0637\u0644\u0629 \u0639\u0644\u0649 \u0628\u062d\u064a\u0631\u0627\u0646 \u0627\u0644\u062e\u0627\u0646 \u0644\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0631\u062c\u0627\u0621 \u0627\u0631\u0633\u0627\u0644 \u0631\u0633\u0627\u0644\u0629 \u0639\u0644\u0649 \u0627\u0644\u062e\u0627\u0635 \u0648\u0634\u0643\u0631\u0627<\/p>\n","protected":false},"author":472,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-35002","post","type-post","status-publish","format-standard","hentry","category-26"],"_links":{"self":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/35002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/users\/472"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/comments?post=35002"}],"version-history":[{"count":0,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/35002\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/media?parent=35002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/categories?post=35002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/tags?post=35002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}