{"id":116654,"date":"2015-09-26T18:26:01","date_gmt":"2015-09-26T16:26:01","guid":{"rendered":"http:\/\/localhost\/wordpress\/?p=116654"},"modified":"2015-09-26T18:26:01","modified_gmt":"2015-09-26T16:26:01","slug":"%d8%ad%d8%af-%d9%8a%d9%82%d8%af%d8%b1-%d8%a7%d9%8a%d9%8a%d8%a8%d9%84%d9%8a-%d8%ae%d8%b5%d9%85-%d9%84%d9%84%d8%ac%d9%8a%d9%85%d8%b3-%d9%8a%d9%88%d9%83%d9%86-%d8%af%d9%8a%d9%86%d8%a7%d9%84%d9%8a","status":"publish","type":"post","link":"https:\/\/www.satfrequencies.com\/invest\/%d8%ad%d8%af-%d9%8a%d9%82%d8%af%d8%b1-%d8%a7%d9%8a%d9%8a%d8%a8%d9%84%d9%8a-%d8%ae%d8%b5%d9%85-%d9%84%d9%84%d8%ac%d9%8a%d9%85%d8%b3-%d9%8a%d9%88%d9%83%d9%86-%d8%af%d9%8a%d9%86%d8%a7%d9%84%d9%8a\/","title":{"rendered":"\u062d\u062f \u064a\u0642\u062f\u0631 \u0627\u064a\u064a\u0628\u0644\u064a \u062e\u0635\u0645 \u0644\u0644\u062c\u064a\u0645\u0633 \u064a\u0648\u0643\u0646 \u062f\u064a\u0646\u0627\u0644\u064a"},"content":{"rendered":"<div>\n<p align=\"center\" style=\"font:bold 16px 'Times New Roman';line-height:170%;\">\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645\u060c\u060c<\/p>\n<p>\u0641\u064a \u0627\u062d\u062f \u0639\u0646\u062f\u0647 \u062e\u0635\u0645 \u0627\u0648 \u064a\u062e\u0628\u0631\u0646\u064a \u0639\u0646 \u0637\u0631\u064a\u0642\u0629 \u0627\u062d\u0635\u0644 \u0641\u064a\u0647 \u062e\u0635\u0645 \u0627\u0648 \u0645\u0646 \u0645\u0643\u0627\u0646 \u064a\u0628\u064a\u0639 \u064a\u0648\u0643\u0646 \u062f\u064a\u0646\u0627\u0644\u064a \u0628\u0633\u0639\u0631 \u0627\u0631\u062e\u0635 \u0645\u0646 \u0627\u0644\u0648\u0643\u0627\u0644\u0629<\/p>\n<p> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645\u060c\u060c \u0641\u064a \u0627\u062d\u062f \u0639\u0646\u062f\u0647 \u062e\u0635\u0645 \u0627\u0648 \u064a\u062e\u0628\u0631\u0646\u064a \u0639\u0646 \u0637\u0631\u064a\u0642\u0629 \u0627\u062d\u0635\u0644 \u0641\u064a\u0647 \u062e\u0635\u0645 \u0627\u0648 \u0645\u0646 \u0645\u0643\u0627\u0646 \u064a\u0628\u064a\u0639 \u064a\u0648\u0643\u0646 \u062f\u064a\u0646\u0627\u0644\u064a \u0628\u0633\u0639\u0631 \u0627\u0631\u062e\u0635 \u0645\u0646 \u0627\u0644\u0648\u0643\u0627\u0644\u0629<\/p>\n","protected":false},"author":204,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-116654","post","type-post","status-publish","format-standard","hentry","category-21"],"_links":{"self":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/116654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/users\/204"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/comments?post=116654"}],"version-history":[{"count":0,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/116654\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/media?parent=116654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/categories?post=116654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/tags?post=116654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}