{"id":108204,"date":"2012-12-14T13:03:38","date_gmt":"2012-12-14T11:03:38","guid":{"rendered":"http:\/\/localhost\/wordpress\/?p=108204"},"modified":"2012-12-14T13:03:38","modified_gmt":"2012-12-14T11:03:38","slug":"%d9%85%d9%83%d9%8a%d9%86%d8%a9-%d9%8a%d8%a7%d9%85%d8%a7%d9%87%d8%a7-75%d8%ad%d8%b5%d8%a7%d9%86-2010-%d8%a8%d8%a7%d9%84%d9%83%d8%b1%d8%aa%d9%88%d9%86-%d9%84%d9%84%d8%a8%d9%8a%d8%b9","status":"publish","type":"post","link":"https:\/\/www.satfrequencies.com\/invest\/%d9%85%d9%83%d9%8a%d9%86%d8%a9-%d9%8a%d8%a7%d9%85%d8%a7%d9%87%d8%a7-75%d8%ad%d8%b5%d8%a7%d9%86-2010-%d8%a8%d8%a7%d9%84%d9%83%d8%b1%d8%aa%d9%88%d9%86-%d9%84%d9%84%d8%a8%d9%8a%d8%b9\/","title":{"rendered":"\u0645\u0643\u064a\u0646\u0629 \u064a\u0627\u0645\u0627\u0647\u0627 75\u062d\u0635\u0627\u0646 2010 \u0628\u0627\u0644\u0643\u0631\u062a\u0648\u0646 \u0644\u0644\u0628\u064a\u0639"},"content":{"rendered":"<div>\n<p>\t\t\t\t\t\t\t\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0627\u062e\u0648\u0627\u0646\u064a \u0639\u0646\u062f\u064a \u0645\u0643\u064a\u0646\u0647 75 \u064a\u0627\u0645\u0627\u0647\u0627 \u0628\u0627\u0644\u0643\u0631\u062a\u0648\u0646 \u0644\u0644\u0628\u064a\u0639 \u0645\u0648\u062f\u064a\u0644 2010 \u062c\u064a\u0643 \u064a\u062f\u0648\u064a \u0645\u0637\u0644\u0648\u0628 15000 \u0648\u0644\u0643\u0645 \u062c\u0632\u064a\u0644 \u0627\u0644\u0634\u0643\u0631<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/6d4e665651.jpg\" border=\"0\" alt=\"\" \/><br \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/b6477554af.jpg\" border=\"0\" alt=\"\" \/><br \/><img decoding=\"async\" src=\"http:\/\/www.satfrequencies.com\/invest\/images\/uploads\/5ddf5d1ab1.jpg\" border=\"0\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0633\u0644\u0627\u0645 \u0639\u0644\u064a\u0643\u0645 \u0627\u062e\u0648\u0627\u0646\u064a \u0639\u0646\u062f\u064a \u0645\u0643\u064a\u0646\u0647 75 \u064a\u0627\u0645\u0627\u0647\u0627 \u0628\u0627\u0644\u0643\u0631\u062a\u0648\u0646 \u0644\u0644\u0628\u064a\u0639 \u0645\u0648\u062f\u064a\u0644 2010 \u062c\u064a\u0643 \u064a\u062f\u0648\u064a \u0645\u0637\u0644\u0648\u0628 15000 \u0648\u0644\u0643\u0645 \u062c\u0632\u064a\u0644 \u0627\u0644\u0634\u0643\u0631<\/p>\n","protected":false},"author":185,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-108204","post","type-post","status-publish","format-standard","hentry","category-22"],"_links":{"self":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/108204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/users\/185"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/comments?post=108204"}],"version-history":[{"count":0,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/posts\/108204\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/media?parent=108204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/categories?post=108204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satfrequencies.com\/invest\/wp-json\/wp\/v2\/tags?post=108204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}